{"id":200,"date":"1997-08-22T01:09:57","date_gmt":"1997-08-22T06:09:57","guid":{"rendered":"http:\/\/yokim.net\/wp\/a\/200\/"},"modified":"1997-08-22T01:09:57","modified_gmt":"1997-08-22T06:09:57","slug":"las-guerras-pnicas","status":"publish","type":"post","link":"https:\/\/yokim.net\/es\/200","title":{"rendered":"Las Guerras P\u00fanicas"},"content":{"rendered":"<p>Las Guerras P\u00fanicas<\/p>\n<p>Curso: 1\u00b0M C<br \/>\nAsignatura: Ciencias Sociales<br \/>\nProfesor: Juan Salinas<br \/>\nAlumno: Yongho Kim<br \/>\nFecha: 22\/08\/\u201997<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/yokim.net\/es\/200\/#Introduccion-Prologo\" >Introducci\u00f3n-Prologo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/yokim.net\/es\/200\/#I_Guerra_Punica_264-241_AC\" >I Guerra P\u00fanica (264-241 AC)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/yokim.net\/es\/200\/#Antecedentes\" >Antecedentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/yokim.net\/es\/200\/#Motivos\" >Motivos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/yokim.net\/es\/200\/#Desarrollo_de_la_Guerra\" >Desarrollo de la Guerra<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/yokim.net\/es\/200\/#Consecuencias\" >Consecuencias<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/yokim.net\/es\/200\/#II_Guerra_Punica_219-202_AC\" >II Guerra P\u00fanica (219-202 AC)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/yokim.net\/es\/200\/#Antecedentes-2\" >Antecedentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/yokim.net\/es\/200\/#Motivos-2\" >Motivos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/yokim.net\/es\/200\/#Desarrollo_de_la_Guerra-2\" >Desarrollo de la Guerra<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/yokim.net\/es\/200\/#Consecuencias-2\" >Consecuencias<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/yokim.net\/es\/200\/#III_Guerra_Punica_149-147_AC\" >III Guerra P\u00fanica (149-147 AC)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/yokim.net\/es\/200\/#Antecedentes-3\" >Antecedentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/yokim.net\/es\/200\/#Motivos-3\" >Motivos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/yokim.net\/es\/200\/#Desarrollo_de_la_Guerra-3\" >Desarrollo de la Guerra<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/yokim.net\/es\/200\/#Consecuencias-3\" >Consecuencias<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/yokim.net\/es\/200\/#Bibliografia\" >Bibliograf\u00eda<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Introduccion-Prologo\"><\/span>Introducci\u00f3n-Prologo <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Algunos escritores dicen, no con falta de raz\u00f3n, que la introducci\u00f3n es lo m\u00e1s dif\u00edcil en un libro. Estoy completamente de acuerdo con ellos (especialmente cuando se trata de informes de C. Sociales); \u00bfC\u00f3mo introducir al lector, que vive la realidad que siente, a una realidad que existi\u00f3 hace cientos de a\u00f3s y que ahora no queda ni un rastro? Esto es muy dif\u00edcil, aunque se tenga en cuenta que el lector ya maneja el problema, pero muy did\u00e1ctico tambi\u00e9n -seg\u00fan y c\u00f3mo se considere- ya que \u00e9sta es la \u00fanica secci\u00f3n donde se permite escribir con contenido humanitario, y no como las dem\u00e1s partes, donde todo debe ser formal y bajo las reglas. La lectura de una introducci\u00f3n es casi siempre MUY interesante (\u00bfo ser\u00e9 yo el \u00fanico que ha le\u00eddo, una tarde despejada, una agradable introducci\u00f3n de un informativo m\u00e9dico?). Como sabr\u00e1n, \u00e9sta secci\u00f3n es introducci\u00f3n, as\u00ed que\u2026 \u00a1escribid libremente!<\/p>\n<p>Pero nos estamos desviando de nuestro objetivo principal, que es la de introducir.<\/p>\n<p>Bueno; lo que pasa, para los lectores despistados, es que hace m\u00e1s de dos mil a\u00f3s existieron dos pueblos que se llamaban Roma y Cartago. Roma os sonar\u00e1 muy familiar a todos, pero \u00bfCartago? \u00bfeso se come? No, desafortunadamente para los que est\u00e1n esperando ansiosamente la hora del almuerzo, pero Cartago era una antigua colonia fenicia fundada a fines del siglo IX AC. Para suerte de cartaginenses y avaros, Cartago se desarroll\u00f3 r\u00e1pidamente gracias a la agricultura y al comercio, dominando extensas costas del norte de Africa, Sicilia, Cerde\u00e1 y las costas sure\u00e1s de Espa\u00e1, con lo que pas\u00f3 a controlar el mediterr\u00e1neo occidental. Pronto se encontr\u00f3 con Roma, con quien se uni\u00f3 para derrotar al gran general griego, Pirro. Pero tras derrotar a Pirro, debi\u00f3 luchar con Roma; pobres cartaginenses. En las tres guerras que entablaron durante un siglo y algo m\u00e1s, no lograron ganar ni una, y finalmente fueron destruidas completamente. Triste ep\u00edlogo para un pueblo que prosper\u00f3 m\u00e1s de medio milenio.<\/p>\n<p>En fin, veamos ahora (aunque parece ser muy temprano a\u00fan) las posibles introducciones: Roma, un pueblo guerrero sediento de sangre, destruy\u00f3 sin compasi\u00f3n a los d\u00e9biles cartaginenses; esto del punto de vista de los vencidos. Si lo vemos con el criterio del triunfador, Roma logr\u00f3 acabar con el monopolio comercial que injustamente pretend\u00eda el ambicioso Cartago y asegur\u00f3 paz y libertad a lo largo del Mediterr\u00e1neo. Hay otros que dicen que \u00e9sta s\u00f3lo fue una m\u00e1s de las numerosas guerras entre los semitas y los no semitas. \u00bfTodos suenan bien? Pues estos no son m\u00e1s que propaganda de cada bando. Lo que en realidad ocurri\u00f3, eran los t\u00edpicos conflictos que ocurren cuando surgen dos o m\u00e1s pueblos dominantes en determinado sectores previligiados. Bueno, \u00bfqu\u00e9 ten\u00eda de especial el Mediterr\u00e1neo? Entre otras cosas, su clima, en especial agradable, tambi\u00e9n era centro de activas relaciones comerciales mar\u00edtimos, limitaba con dos de las grandes cultras antiguas: Egipto y Mesopotamia. Esto y otras m\u00e1s, movieron a los dos pueblos a entablar guerra por el dominio de ella, de la cual Roma, que ten\u00eda m\u00e1s factores a su favor, sali\u00f3 vencedor.<\/p>\n<p>En las siguientes p\u00e1ginas, ud. podr\u00e1 disfrutar de informaci\u00f3n detallada sobre los sucesos m\u00e1s relevantes de una guerra que dur\u00f3 m\u00e1s de cincuenta a\u00f3s: Las Guerras P\u00fanicas.<br \/>\n<!--more--><\/p>\n<h2><span class=\"ez-toc-section\" id=\"I_Guerra_Punica_264-241_AC\"><\/span>I Guerra P\u00fanica (264-241 AC) <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"Antecedentes\"><\/span>Antecedentes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El mundo conocido, en estos tiempos, estaba dividido fundamentalmente en cuatro grandes potencias: la rep\u00fablica cartaginense en Cartago, C\u00f3rcega, Sicilia y parte de Espa\u00e1; Roma, en casi toda la pen\u00ednsula it\u00e1lica, excepto la galia cisalpina; la dinast\u00eda Ptolomea en Egipto, y la dinast\u00eda Sel\u00facida en mesopotamia y Siria. Tambi\u00e9n en India reg\u00eda la dinast\u00eda Sunga, pero \u00e9sta no afectaba a las dem\u00e1s potencias, por su lejan\u00eda geogr\u00e1fica. China, la civilizaci\u00f3n restante de las cuatro grandes culturas del mundo antiguo, pasaba por una \u00e9poca de estados feudales.<\/p>\n<p>Las dos grandes potencias helen\u00edsticas, Egipto y Siria, eran influyentes por s\u00ed mismos, pero al estar en constante estado de guerra entre ambos, hab\u00edan desgastado la mayor parte de sus recursos.<\/p>\n<p>Macedonia hab\u00eda perdido la mayor parte de su territorio griego, a excepci\u00f3n de Atenas y territorios menores. Esparta hab\u00eda logrado la independencia; dos grandes ligas, la aquea y la etolia, divid\u00edan a las dem\u00e1s polis libres, siendo bastante peligrosas para Macedonia, pero el desacuerdo entre las polis y las continuas luchas de ambas ligas los hac\u00edan inofensivos para el exterior.<\/p>\n<p>Roma y Cartago hab\u00edan tenido contactos comerciales desde 358, en el que establecieron un pacto de amistad, que medio siglo despu\u00e9s se transform\u00f3 en un tratado de alianza militar (288), cuando luchaban contra el griego Pirro.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Motivos\"><\/span>Motivos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Inevitablemente, cuando se mencionan los motivos, se frecuenta decir: hay una superficial y otra principal. Tenemos aqu\u00ed la superficial: Mesina, colonia griega conquistada por Cartago, pidi\u00f3 ayuda a Roma; Roma acudi\u00f3 (aunque era aliado de Cartago) como buen pueblo guerrero. Pero otra m\u00e1s profunda e importante, era la necesidad de Roma de dominar Sicilia, isla importante en el comercio del mediterr\u00e1neo, y el inevitable choque entre las dos \u00fanicas potencias del mediterr\u00e1neo occidental, del cual se esperaban innumerables beneficios al vencedor.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Desarrollo_de_la_Guerra\"><\/span>Desarrollo de la Guerra<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Sobre el desarrllo de la guerra, la informaci\u00f3n existente es bastante incompleta, pero podemos saber algunos puntos importantes.<\/p>\n<p>Los primeros combates tuvieron en lugar en Sicilia, con victorias romanas, hecho no muy sorprendente si pensamos en que los soldados romanos eran veteranos que hab\u00edan luchado contra el poderoso ej\u00e9rcito de Pirro (275); pero en el aspecto naval, Roma no ten\u00eda posibilidades de triunfo, ya que Roma casi nunca hab\u00eda utilizado barcos, adem\u00e1s de que la potencia naval de Cartago era la m\u00e1xima de la \u00e9poca.<\/p>\n<p>Por estas razones, Roma construy\u00f3 r\u00e1pidamente una gran flota, en el cual fueron de gran valor las ciudades australes recientemente conquistadas, ya que sus habitantes conoc\u00edan bien construir y manejar los barcos. Gracias a estos esfuerzos y a una nueva t\u00e1ctica en el combate naval, Roma logr\u00f3 triunfar en Miles. Aprovechando su triunfo, Roma lanz\u00f3 una campa\u00e1 directa contra Cartago, siendo destru\u00edda completamente. Roma organiz\u00f3 nuevamente un gran ej\u00e9rcito, y derrot\u00f3 la flota de Cartago en Egades (241). Cartago, quedando destru\u00edda sus \u00faltimas fuerzas, firm\u00f3 la paz.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Consecuencias\"><\/span>Consecuencias<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Con la I Guerra p\u00fanica, Roma hab\u00eda dado su primer gran paso hacia el imperio: hab\u00eda obtenido Sicilia, bajo la denominaci\u00f3n de provincia, nombre que se le dar\u00edan a casi todas sus conquistas fuera de Italia. Sicilia, la primera provincia romana, ser\u00eda un importante fuente de alimentaci\u00f3n de Roma. Precisamente aqu\u00ed ser\u00eda donde comenzar\u00eda el cultivo a gran escala, conocido como latifundium.<\/p>\n<p>Tambi\u00e9n logr\u00f3 crear su primera flota naval, por las necesidades, superior a la de cualquier otra potencia, la que expandir\u00eda el campo de dominio de Roma hacia el mar; esta ventaja ser\u00eda una buena amenaza para Cartago en la II guerra p\u00fanica.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"II_Guerra_Punica_219-202_AC\"><\/span>II Guerra P\u00fanica (219-202 AC) <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"Antecedentes-2\"><\/span>Antecedentes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Roma hab\u00eda logrado obtener Cerde\u00e1 y C\u00f3rcega, dominando as\u00ed el mar Tirreno, y hab\u00eda conquistado la Galia Cisalpina. Cartago, en tanto, hab\u00eda conquistado en casi su totalidad la hispania, supliendo en parte las p\u00e9rdidas de Sicilia y Cerde\u00e1.<\/p>\n<p>La situaci\u00f3n en el cercano Oriente no hab\u00eda variado, siendo favorable para Roma esta circunstancia, ya que no necesitaba preocuparse de ataques por la retaguardia.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Motivos-2\"><\/span>Motivos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El motivo que trajo consigo la inmediata reacci\u00f3n romana fue el ataque cartagin\u00e9s a la griega ciudad de Sagunto, protectorado romano. Cartago ten\u00eda diversas y justas razones para iniciar una guerra, siendo la m\u00e1s importante la violaci\u00f3n de paz de los romanos al conquistar Cerde\u00e1 (237), un pretexto para recuperar Sicilia.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Desarrollo_de_la_Guerra-2\"><\/span>Desarrollo de la Guerra<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>El general cartagin\u00e9s An\u00edbal, hijo de Alm\u00edcar-conquistador de Hispania-, prepar\u00f3 y entren\u00f3 en Hispania un gran ej\u00e9rcito. Con la casi totalidad de \u00e9ste, formado por unos 60.000 soldados, se dirigi\u00f3 a la Galia cisalpina, territorio norte de Roma; cruz\u00f3 los Alpes (218) -probablemente no utiliz\u00f3 transporte mar\u00edtimo por los riesgos que \u00e9sto significaba con la poderosa flota de Roma-, y con algunos problemas (perdi\u00f3 la mayor parte de los soldados por ataque de galos) logr\u00f3 entrar en Italia. El grueso de las tropas romanas no estaban presentes en la zona, as\u00ed que An\u00edbal logr\u00f3 triunfar en el primer combate y ganar terreno ventajoso, a pesar de que s\u00f3lo ten\u00eda 20.000 soldados sobrevivientes. Despu\u00e9s de esta victoria, obtuvo la ayuda de los galos, quienes se levantaron contra Roma, ofreciendo unos 60.000 hombres. Desde entonces, aprovechando su capacidad militar, obtuvo victoria tras victoria en las batallas de Tesino (218), Trebia y Tresinato (217), y Cannas (216), moviliz\u00e1ndose hacia el sur, esquivando la ciudad de Roma, que no le habr\u00eda sido muy dif\u00edcil conquistar.<\/p>\n<p>An\u00edbal esperaba que, despu\u00e9s de las derrotas romanas, los aliados se levantaran en masa; no ocurri\u00f3 as\u00ed, pero algunas ciudades, entre ellas Cap\u00faa y Siracusa, se unieron a Cartago. El prop\u00f3sito de An\u00edbal era dar algunas tierras a galos, otras a griegos, y recuperar otras para Cartago, reduciendo as\u00ed Roma en uno m\u00e1s de los muchos pa\u00edses que gobernaran la pen\u00ednsula it\u00e1lica; aqu\u00ed estaba su error. Ofreci\u00f3 la paz a Roma, pero \u00e9sta lo rechaz\u00f3. Si An\u00edbal hubiese tomado Roma, el transcurso de la guerra habr\u00eda sido, tal vez, diferente. Roma sacaba provecho del gran recurso humano que pose\u00eda y repon\u00eda r\u00e1pidamente su ej\u00e9rcito despu\u00e9s de cada derrota. An\u00edbal se vi\u00f3 obligado a mantenerse, finalmente, defendiendo las tierras conquistadas; su ej\u00e9rcito se agotaba, y a partir del a\u00f3 214, la balanza se irgui\u00f3 a favor de Roma.<\/p>\n<p>Roma recuper\u00f3 Siracusa y Cap\u00faa (211), aniquil\u00f3 los refuerzos venidos de Hispania (207) y tom\u00f3 C\u00e1diz (206). Cartago decidi\u00f3 abandonar hispania despu\u00e9s de todas las derrotas, lo que facilit\u00f3 a\u00fan m\u00e1s las victorias romanas, que conquistaron Hispania, declar\u00e1ndolo provincia romana.<\/p>\n<p>Finalmente, Roma decidi\u00f3 acabar con la guerra y envi\u00f3 una expedici\u00f3n directa contra Cartago. An\u00edbal, quien tuvo que regresar r\u00e1pidamente de Italia, se enfrent\u00f3 con Escipi\u00f3n, general romano, pero fue derrotado en la batalla de Zama (202), firmando luego la paz. Cartago se comprometi\u00f3 a pagar tributo por cincuenta a\u00f3s, no declarar guerra a pueblo alguno sin permiso de Roma, y a entregar todos sus naves de guerra, as\u00ed como sus elefantes y caballos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Consecuencias-2\"><\/span>Consecuencias<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>La II guerra p\u00fanica hab\u00eda sido la decisiva para el futuro de Cartago y Roma. Desde ahora Roma se expandir\u00eda inmensamente, sin encontrar amenaza exterior, a excepci\u00f3n de b\u00e1rbaros del norte, y Cartago experimentar\u00eda una corta recuperaci\u00f3n, para luego desaparecer.<\/p>\n<p>Entre los varios puntos de vista de sus consecuencias, la p\u00e9rdida de Roma habr\u00eda cambiado dr\u00e1sticamente el aspecto exterior de este informe; no estar\u00eda escrito en castellano, sino tal vez en alg\u00fan dialecto lejano de la lengua cartaginensa o \u00e1rabe\u2026 qui\u00e9n sabe.<\/p>\n<p>Cartago hab\u00eda sido, el \u00fanico (desde sus comienzos hasta su ocaso) oponente organizado de Roma; Roma no hallar\u00eda otra potencia capaz de enfrent\u00e1rsele, y esto probablemente fue otra de las causas que motiv\u00f3 al auge del helenismo (y sus lujos) en Roma, libre ya de problemas econ\u00f3micos-pol\u00edticos, y por esto habr\u00eda acelerado tambi\u00e9n las luchas sociales, ansiosos de obtener el mayor provecho posible de las ganancias.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"III_Guerra_Punica_149-147_AC\"><\/span>III Guerra P\u00fanica (149-147 AC) <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h3><span class=\"ez-toc-section\" id=\"Antecedentes-3\"><\/span>Antecedentes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>M\u00e1s de cincuenta a\u00f3s hab\u00edan pasado del t\u00e9rmino de la segunda guerra p\u00fanica. De las huellas de la guerra ya no quedaban en los nuevos habitantes de Roma y Cartago. Cartago se hab\u00eda recuperado casi completamente, en el aspecto econ\u00f3mico, de la derrota; la actividad comercial fue su principal promotor.<\/p>\n<p>Roma, en tanto, estaba comenzando a hundirse en la nueva cultura helen\u00edstica que hab\u00eda llegado de las conquistas del oriente: Macedonia, Grecia y Asia menor.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Motivos-3\"><\/span>Motivos<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Roma, al ver un Cartago completamente recuperada, temi\u00f3 que \u00e9sta invadiese otra vez Roma, y comenz\u00f3 a preparar el \u00faltimo golpe a Cartago. Un personaje que incit\u00f3 fuertemente al gobierno romano a inclinarse por esta opci\u00f3n fue Cat\u00f3n, anciano soldado romano de la \u00e9poca de la II guerra p\u00fanica, quien vi\u00f3 por s\u00ed mismo las riquezas del nuevo Cartago, e inici\u00f3 una fuerte propaganda en contra de Cartago, apoyado por comerciantes que quer\u00edan monopolizar el comercio del Mediterr\u00e1neo, y trat\u00f3 de convencer al pueblo y el Senado, lo que logr\u00f3 finalmente.<\/p>\n<p>Despu\u00e9s de todo, Roma hab\u00eda firmado un tratado de paz con Cartago, y siendo Roma superior a Cartago, deb\u00eda existir una excusa para atacar Cartago sin recibir cr\u00edticas internacionales. Esta la proporcionaron el mismo Cartago, declarando la guerra a los n\u00famidas -pueblo que ven\u00eda molestando Cartago desde a\u00f3s- lo cual estaba prohibido sin permiso de Roma.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Desarrollo_de_la_Guerra-3\"><\/span>Desarrollo de la Guerra<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Roma, reclamando la violaci\u00f3n del tratado de paz, desembarc\u00f3 sus tropas en Cartago. Los habitantes cartaginenses, atemorizados por la invasi\u00f3n, entregaron las pocas armas que hab\u00edan fabricado y se comprometieron a anular la guerra. Pero tan pronto hicieron esto, recibieron \u00f3rdenes de abandonar la ciudad y movilizarse a zonas alejadas. Esto caus\u00f3 indignaci\u00f3n en Cartago, quien decidi\u00f3 defender la ciudad hasta el fin. De todos modos, la guerra fue corta. Tras dos a\u00f3s de asedio, y bajo el mando de Escipi\u00f3n Emiliano, Roma tom\u00f3 Cartago. A las \u00f3rdenes del Senado romano, los soldados incendiaron la ciudad y araron sus tierras, prohibiendo reconstruir la ciudad.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Consecuencias-3\"><\/span>Consecuencias<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>En realidad, las consecuencias de esta tercera guerra no fueron muchas. Podr\u00edamos citar, a lo m\u00e1s que el anciano Cat\u00f3n debi\u00f3 de sentirse feliz, entre otras cosas, y que desapareci\u00f3 la presi\u00f3n psicol\u00f3gica de la existencia de Cartago. Al sentirse completamente relajados al no haber presi\u00f3n militar, econ\u00f3mica ni psicol\u00f3gica del exterior, los ciudadanos romanos habr\u00edan acelerado, las futuras luchas sociales, vertiendo sus energ\u00edas sobrantes en ello.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Bibliografia\"><\/span>Bibliograf\u00eda <span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Historia Universal\/Roma-Carl Grimberg<br \/>\nEsbozo de la historia occidental- SukHong Min <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las Guerras P\u00fanicas Curso: 1\u00b0M C Asignatura: Ciencias Sociales Profesor: Juan Salinas Alumno: Yongho Kim Fecha: 22\/08\/\u201997 Introducci\u00f3n-Prologo Algunos escritores dicen, no con falta de raz\u00f3n, que la introducci\u00f3n es lo m\u00e1s dif\u00edcil en un libro. Estoy completamente de acuerdo con ellos (especialmente cuando se trata de informes de C. Sociales); \u00bfC\u00f3mo introducir al lector, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[379,354,347],"tags":[],"class_list":["post-200","post","type-post","status-publish","format-standard","hentry","category-es-a","category-front-2","category-s-2"],"_links":{"self":[{"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/posts\/200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/comments?post=200"}],"version-history":[{"count":0,"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/posts\/200\/revisions"}],"wp:attachment":[{"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/media?parent=200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/categories?post=200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yokim.net\/es\/wp-json\/wp\/v2\/tags?post=200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}